{"id":21,"count":0,"description":"","link":"https:\/\/spectralict.com\/index.php\/product-category\/accessories\/","name":"Accessories","slug":"accessories","taxonomy":"product_cat","parent":0,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/spectralict.com\/index.php\/product-category\/accessories\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/21\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spectralict.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spectralict.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/index.php\\\/store\\\/#listItem\",\"name\":\"Store\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/index.php\\\/store\\\/#listItem\",\"position\":2,\"name\":\"Store\",\"item\":\"https:\\\/\\\/spectralict.com\\\/index.php\\\/store\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/index.php\\\/product-category\\\/accessories\\\/#listItem\",\"name\":\"Accessories\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spectralict.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/index.php\\\/product-category\\\/accessories\\\/#listItem\",\"position\":3,\"name\":\"Accessories\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/index.php\\\/store\\\/#listItem\",\"name\":\"Store\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/21\\\/#collectionpage\",\"url\":\"https:\\\/\\\/spectralict.com\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/21\\\/\",\"name\":\"Accessories - spectralict.com\",\"inLanguage\":\"en-AU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spectralict.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spectralict.com\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/21\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/#organization\",\"name\":\"spectralict.com\",\"description\":\"Cyber Security from Spectral ICT\",\"url\":\"https:\\\/\\\/spectralict.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/spectralict.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/cropped-SpectralICT-logo-web-200x200-1.png\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/21\\\/#organizationLogo\",\"width\":176,\"height\":66},\"image\":{\"@id\":\"https:\\\/\\\/spectralict.com\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/21\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spectralict.com\\\/#website\",\"url\":\"https:\\\/\\\/spectralict.com\\\/\",\"name\":\"spectralict.com\",\"description\":\"Cyber Security from Spectral ICT\",\"inLanguage\":\"en-AU\",\"publisher\":{\"@id\":\"https:\\\/\\\/spectralict.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Accessories - spectralict.com","description":"","canonical_url":"https:\/\/spectralict.com\/index.php\/product-category\/accessories\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/spectralict.com\/wp-json\/wp\/v2\/product_cat\/21\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/spectralict.com#listItem","position":1,"name":"Home","item":"https:\/\/spectralict.com","nextItem":{"@type":"ListItem","@id":"https:\/\/spectralict.com\/index.php\/store\/#listItem","name":"Store"}},{"@type":"ListItem","@id":"https:\/\/spectralict.com\/index.php\/store\/#listItem","position":2,"name":"Store","item":"https:\/\/spectralict.com\/index.php\/store\/","nextItem":{"@type":"ListItem","@id":"https:\/\/spectralict.com\/index.php\/product-category\/accessories\/#listItem","name":"Accessories"},"previousItem":{"@type":"ListItem","@id":"https:\/\/spectralict.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/spectralict.com\/index.php\/product-category\/accessories\/#listItem","position":3,"name":"Accessories","previousItem":{"@type":"ListItem","@id":"https:\/\/spectralict.com\/index.php\/store\/#listItem","name":"Store"}}]},{"@type":"CollectionPage","@id":"https:\/\/spectralict.com\/wp-json\/wp\/v2\/product_cat\/21\/#collectionpage","url":"https:\/\/spectralict.com\/wp-json\/wp\/v2\/product_cat\/21\/","name":"Accessories - spectralict.com","inLanguage":"en-AU","isPartOf":{"@id":"https:\/\/spectralict.com\/#website"},"breadcrumb":{"@id":"https:\/\/spectralict.com\/wp-json\/wp\/v2\/product_cat\/21\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/spectralict.com\/#organization","name":"spectralict.com","description":"Cyber Security from Spectral ICT","url":"https:\/\/spectralict.com\/","logo":{"@type":"ImageObject","url":"https:\/\/spectralict.com\/wp-content\/uploads\/2022\/05\/cropped-SpectralICT-logo-web-200x200-1.png","@id":"https:\/\/spectralict.com\/wp-json\/wp\/v2\/product_cat\/21\/#organizationLogo","width":176,"height":66},"image":{"@id":"https:\/\/spectralict.com\/wp-json\/wp\/v2\/product_cat\/21\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/spectralict.com\/#website","url":"https:\/\/spectralict.com\/","name":"spectralict.com","description":"Cyber Security from Spectral ICT","inLanguage":"en-AU","publisher":{"@id":"https:\/\/spectralict.com\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/spectralict.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/spectralict.com\/index.php\/store\/\" title=\"Store\">Store<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAccessories\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/spectralict.com"},{"label":"Store","link":"https:\/\/spectralict.com\/index.php\/store\/"},{"label":"Accessories","link":"https:\/\/spectralict.com\/index.php\/product-category\/accessories\/"}],"_links":{"self":[{"href":"https:\/\/spectralict.com\/index.php\/wp-json\/wp\/v2\/product_cat\/21"}],"collection":[{"href":"https:\/\/spectralict.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/spectralict.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/spectralict.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}